{"id":4908,"date":"2024-03-04T14:13:55","date_gmt":"2024-03-04T13:13:55","guid":{"rendered":"https:\/\/www.asimas.it\/new_asimas\/?p=4908"},"modified":"2024-03-15T18:05:37","modified_gmt":"2024-03-15T17:05:37","slug":"mastocitosi-20-anni-dopo","status":"publish","type":"post","link":"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/","title":{"rendered":"MASTOCITOSI: 20 ANNI DOPO"},"content":{"rendered":"\n<p><strong>MASTOCITOSI: 20 ANNI DOPO<\/strong><\/p>\n\n\n\n<p><strong>29 Febbraio &#8211; 1 Marzo 2024:<\/strong> due giornate che resteranno indelebili nella memoria di tutti noi di Asimas. Invitati al congresso &#8220;DRIVE THE CHANGE&#8221; sponsorizzato da Blueprint Medicine, abbiamo assistito a un evento storico: la medicina di precisione applicata alla mastocitosi sistemica, una svolta epocale che apre nuovi orizzonti per la cura di questa malattia rara.<\/p>\n\n\n\n<p><strong>Un cambio di rotta che profuma di speranza<\/strong><\/p>\n\n\n\n<p>Finalmente, dopo anni di buio e incertezza, si parla di terapia mirata, di un approccio che combatte la malattia alla radice e non solo i suoi sintomi. Un sogno ad occhi aperti per chi, come noi, combatte contro la mastocitosi da anni.<\/p>\n\n\n\n<p><strong>Era il 2006<\/strong> quando il Professor Triggiani diede vita al Network Italiano ed Europeo a Napoli. All&#8217;epoca non c&#8217;era nulla, solo il buio pi\u00f9 totale. Da quel primo incontro \u00e8 nata Asimas, un ponte tra pazienti, clinici e ricerca scientifica. Un ponte che ha resistito per quasi vent&#8217;anni, grazie al lavoro instancabile di tutti noi. Un lavoro a tratti faticoso, ma sostenuto da una forza inarrestabile: la voglia di dare una vita migliore a chi, come noi, convive con questa malattia.<\/p>\n\n\n\n<p><strong>DRIVE THE CHANGE \u00e8 stato un full immersion di emozioni<\/strong><\/p>\n\n\n\n<p>Il contatto con la comunit\u00e0 scientifica, la loro solidariet\u00e0 e affetto, i nuovi medici preparati e accoglienti, la professionalit\u00e0 di Blueprint che dedica tempo alla sfera emotiva dei pazienti: tutto questo ha reso l&#8217;evento un&#8217;esperienza indimenticabile.<\/p>\n\n\n\n<p><strong>E poi la sorpresa:<\/strong> la magnifica torta con il LOGO della giornata mondiale delle malattie rare, ed il viola che rappresenta la giornata Internazionale della\u00a0Mastocitosi e Disordini mastocitari: per essere presenti e sensibilizzare con tutti i rari del mondo in un momento di gioia e condivisione insieme a tutti i medici abbiamo acceso anche noi\u00a0i riflettori su tutte le patologie rare troppo spesso dimenticate!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" src=\"http:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/torta_logo_malattie_rare.jpg\" alt=\"Torta con il logo delle malattie rare\" class=\"wp-image-4999\" width=\"478\" height=\"353\" srcset=\"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/torta_logo_malattie_rare.jpg 790w, https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/torta_logo_malattie_rare-300x222.jpg 300w, https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/torta_logo_malattie_rare-768x568.jpg 768w\" sizes=\"(max-width: 478px) 100vw, 478px\" \/><\/figure>\n\n\n\n<br>\n\n\n\n<p><strong>Asimas c&#8217;\u00e8, c&#8217;\u00e8 sempre stata e ci sar\u00e0 sempre<\/strong><\/p>\n\n\n\n<p>In questi vent&#8217;anni abbiamo lottato fianco a fianco con la comunit\u00e0 medica e i ricercatori, mantenendo unita la nostra piccola grande famiglia. Abbiamo sostenuto la ricerca, finanziato progetti, organizzato eventi e campagne di sensibilizzazione. Non ci siamo mai arresi, neanche nei momenti pi\u00f9 bui.<\/p>\n\n\n\n<p><strong>E ora, finalmente, possiamo dire che la nostra tenacia \u00e8 stata premiata<\/strong> <strong>e<\/strong> t<strong>utto questo \u00e8 stato possibile grazie ad Asimas!<\/strong><\/p>\n\n\n\n<p>Grazie a quel ponte che abbiamo costruito e mantenuto saldo per vent&#8217;anni. Un ponte che ha unito persone, competenze, speranze e sogni. Un ponte che ha fatto la differenza, e che continuer\u00e0 a fare la differenza nel futuro della mastocitosi.<\/p>\n\n\n\n<p><strong>Non \u00e8 una vittoria solo nostra, ma di tutti!<\/strong> Di chi ha sofferto, di chi ha lottato, di chi ha creduto in un futuro migliore. Un futuro che, finalmente, \u00e8 ad un passo da noi.<\/p>\n\n\n\n<p>Abbiamo raccolto documenti e articoli di giornale con informazioni complete e aggiornate <strong>del congresso DRIVE THE CHANGE <\/strong>e rivivere l&#8217;entusiasmo di quei giorni con &nbsp;le ultime novit\u00e0 sulla ricerca e i trattamenti per la mastocitosi.<\/p>\n\n\n\n<br>\n\n\n\n<p><\/p>\n\n\n\n<p><span style=\"color: #ff0000;\"><strong>Intervista alla nostra Presidente Patrizia Marcis<\/strong><\/span><\/p>\n\n\n\n<p><strong>\u201cFondamentale la collaborazione tra Associazioni pazienti, medici specialisti e aziende farmaceutiche per una migliore gestione della mastocitosi\u201d<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.asimas.it\/new_asimas\/4_intervista_marcis\/\" target=\"_blank\" rel=\"noopener\"><strong>Apri il PDF &gt;&gt;&gt;&gt;<\/strong><\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><span style=\"color: #ff0000;\"><strong>La voce degli esperti:<\/strong><\/span><\/p>\n\n\n\n<p><strong>Massimo Triggiani,<\/strong>&nbsp;Chair of the European Competence Network on Mastocytosis (ECNM), spiega come le terapie di precisione e i farmaci selettivi stanno cambiando la storia della malattia.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.asimas.it\/new_asimas\/2_intervista_triggiani\/\" target=\"_blank\" rel=\"noopener\"><strong>Apri il PDF &gt;&gt;&gt;&gt;<\/strong><\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>Roberta Zanotti,<\/strong>&nbsp;Presidente Rete Italiana Mastocitosi \u2013 RIMA, parla dell&#8217;importanza della diagnosi precoce e dei centri specializzati.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.asimas.it\/new_asimas\/3_intervista-_zanotti\/\" target=\"_blank\" rel=\"noopener\"><strong>Apri il PDF &gt;&gt;&gt;&gt;<\/strong><\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong><br>Giacomo Baruchello,<\/strong>&nbsp;Vice Presidente, Regional &amp; General Manager Italy &amp; Iberia, Blueprint Medicines, illustra l&#8217;impegno dell&#8217;azienda nello sviluppo di terapie innovative per la mastocitosi.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.asimas.it\/new_asimas\/5_intervista_baruchello\/\" target=\"_blank\" rel=\"noopener\"><strong>Apri il PDF &gt;&gt;&gt;&gt;<\/strong><\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>Scheda informativa di Blueprint Medicines,<\/strong>&nbsp;un&#8217;azienda globale impegnata nella terapia di precisione per la mastocitosi e altre patologie rare.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/6_Scheda_Patologia.pdf\" target=\"_blank\" rel=\"noopener\">Apri il PDF &gt;&gt;&gt;&gt;<\/a><br><\/strong><\/p>\n\n\n\n<br>\n\n\n\n<p><span style=\"color: #ff0000;\"><strong>Principali articoli di giornale:<\/strong><\/span><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>NAPOLI TODAY:<\/strong><\/p>\n\n\n\n<p>Link all\u2019articolo: <a href=\"https:\/\/www.napolitoday.it\/salute\/mastocitosi-sistemica-convegno-napoli.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.napolitoday.it\/salute\/mastocitosi-sistemica-convegno-napoli.html<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>CORRIERE DELLA SERA:<\/strong><\/p>\n\n\n\n<p>Link all\u2019articolo: <a href=\"https:\/\/napoli.corriere.it\/notizie\/cronaca\/24_marzo_01\/mastocistosi-sistemica-da-napoli-focus-sulle-nuove-terapie-1c596e0a-d1ec-4720-8b9d-64fac8762xlk.shtml\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/napoli.corriere.it\/notizie\/cronaca\/24_marzo_01\/mastocistosi-sistemica-da-napoli-focus-sulle-nuove-terapie-1c596e0a-d1ec-4720-8b9d-64fac8762xlk.shtml<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>GAZZETTA DI NAPOLI:<\/strong><\/p>\n\n\n\n<p>Link all\u2019articolo: <a href=\"https:\/\/www.gazzettadinapoli.it\/rubriche\/salute-e-benessere\/da-napoli-il-punto-sulla-mastocitosi-sistemica-nuove-prospettive-con-la-medicina-di-precisione-e-i-farmaci-selettivi\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.gazzettadinapoli.it\/rubriche\/salute-e-benessere\/da-napoli-il-punto-sulla-mastocitosi-sistemica-nuove-prospettive-con-la-medicina-di-precisione-e-i-farmaci-selettivi\/<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>CRONACHE DI SCIENZA:<\/strong><\/p>\n\n\n\n<p>Link all\u2019articolo: <a href=\"https:\/\/www.cronachediscienza.it\/2024\/03\/01\/mastocitosi-sistemica-nuove-prospettive-con-la-medicina-di-precisione-e-farmaci-selettivi\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.cronachediscienza.it\/2024\/03\/01\/mastocitosi-sistemica-nuove-prospettive-con-la-medicina-di-precisione-e-farmaci-selettivi\/<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>Articolo su ANSA \u2013 ROMA:<\/strong><\/p>\n\n\n\n<p>\u201cIl farmaco mirato colpisce la mutazione driver della malattia In Italia convivono con la mastocitosi sistemica, una patologia caratterizzata dalla proliferazione clonale di mastociti in vari organi, circa 5mila casi di cui circa il 10% con forme avanzate. L&#8217;arrivo di nuove terapie di precisione, pu\u00f2 tuttavia cambiare la vita dei pazienti. Se ne \u00e8 parlato oggi a Napoli in occasione dell&#8217;evento organizzato da Blueprint Medicines &#8216;Drive The Change&#8217;, in presenza dei rappresentati della Rima &#8211; Rete Italiana mastocitosi e associazione pazienti Asimas &#8211; Associazione Italiana mastocitosi. &#8220;Fondamentale, aver capito che era la mutazione Kit nei mastociti a farli proliferare in modo incontrollato e a porli in uno stato di iperattivazione&#8221;, spiega Massimo Triggiani, Chair of the European Competence Network on Mastocytosis (Ecnm), Ordinario di Medicina Interna Dipartimento di Medicina e Chirurgia Universit\u00e0 degli Studi di Salerno e Direttore Uoc Diagnosi e Terapia Malattie Allergiche e Sistema immunitario Aou San Giovanni di Dio e Ruggi d&#8217;Aragona, Salerno.Presupposto per una precoce diagnosi &#8220;\u00e8 che questa venga effettuata presso un Centro dedicato in cui operano diversi specialisti e dotato di strumenti e tecniche diagnostiche appropriate &#8211; sottolinea Roberta Zanotti, presidente Rima e collaboratrice del Gruppo Interdisciplinare per lo Studio della mastocitosi, Uo di Ematologia Aou Integrata di Verona &#8211; attualmente sono pi\u00f9 di 30 distribuiti su quasi tutto il territorio nazionale&#8221;. La sintomatologia che accompagna la mastocitosi sistemica, oltre ad essere debilitante ha un impatto profondo sulla qualit\u00e0 di vita dei pazienti ma &#8220;la luce in fondo al tunnel oggi si vede &#8211; conclude Patrizia Marcis, presidente Asimas &#8211; speriamo che la ricerca prosegua gli studi nel solco tracciato. La collaborazione tra Associazione dei pazienti, medici specialisti e aziende farmaceutiche \u00e8 fondamentale&#8221;.<\/p>\n\n\n\n<br>\n\n\n\n<p><strong>TUTTO SANITA\u2019:<\/strong><\/p>\n\n\n\n<p>Link all\u2019articolo: <a href=\"https:\/\/www.tuttosanita.com\/mastocisti-sistemica-pool-di-esperti-a-napoli-per-un-cambio-di-passo\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.tuttosanita.com\/mastocisti-sistemica-pool-di-esperti-a-napoli-per-un-cambio-di-passo\/<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>NAPOLI VILLAGE:<\/strong><\/p>\n\n\n\n<p>Link all\u2019articolo: <a href=\"https:\/\/www.napolivillage.com\/medicina\/da-napoli-il-punto-sulla-mastocitosi-sistemica-nuove-prospettive-con-la-medicina-di-precisione-e-i-farmaci-selettivi\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.napolivillage.com\/medicina\/da-napoli-il-punto-sulla-mastocitosi-sistemica-nuove-prospettive-con-la-medicina-di-precisione-e-i-farmaci-selettivi\/<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>IL SUD ONLINE:<\/strong><\/p>\n\n\n\n<p>Link all\u2019articolo: <a href=\"https:\/\/www.ilsudonline.it\/da-napoli-il-punto-sulla-mastocitosi-sistemic\">https:\/\/www.ilsudonline.it\/da-napoli-il-punto-sulla-mastocitosi-sistemica<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>ANSA CAMPANIA:<\/strong><\/p>\n\n\n\n<p>Link all\u2019articolo: <a href=\"http:\/\/www.ansa.it\/campania\/notizie\/la_nostra_salute\/2024\/03\/01\/mastocitosi-sistemica-nuove-prospettive-con-medicina-precisione_7944b33f-7526-496d-bccc-d6e928ca0bd8.html\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.ansa.it\/campania\/notizie\/la_nostra_salute\/2024\/03\/01\/mastocitosi-sistemica-nuove-prospettive-con-medicina-precisione_7944b33f-7526-496d-bccc-d6e928ca0bd8.html<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>PREVENZIONE SALUTE:<\/strong><\/p>\n\n\n\n<p>Link all\u2019articolo: <a href=\"https:\/\/prevenzione-salute.it\/57173\/mastocisti-una-terapia-offre-nuove-speranze.html\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/prevenzione-salute.it\/57173\/mastocisti-una-terapia-offre-nuove-speranze.html<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>ALLEATI PER LA SALUTE:<\/strong><\/p>\n\n\n\n<p><meta charset=\"utf-8\">Link all\u2019articolo: <a href=\"https:\/\/www.alleatiperlasalute.it\/ematologia\/mastocitosi\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.alleatiperlasalute.it\/ematologia\/mastocitosi<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>SCISCIANO NOTIZIE:<\/strong><\/p>\n\n\n\n<p><meta charset=\"utf-8\">Link all\u2019articolo: <a href=\"https:\/\/www.sciscianonotizie.it\/napoli-mastocisti-sistemica-pool-di-esperti-per-un-cambio-di-passo\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.sciscianonotizie.it\/napoli-mastocisti-sistemica-pool-di-esperti-per-un-cambio-di-passo\/<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>CILENTO NOTIZIE:<\/strong><\/p>\n\n\n\n<p>Link all\u2019articolo: <a href=\"https:\/\/www.cilentonotizie.it\/dettaglio\/51873\/mastocisti-sistemica-pool-di-esperti-a-napoli-per-un-cambio-di-passo\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.cilentonotizie.it\/dettaglio\/51873\/mastocisti-sistemica-pool-di-esperti-a-napoli-per-un-cambio-di-passo\/<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>MESSINA MEDICA:<\/strong><\/p>\n\n\n\n<p>Link all\u2019articolo: <a href=\"https:\/\/www.messinamedica.it\/2024\/03\/mastocitosi-sistemica-nuove-prospettive-con-la-medicina-di-precisione-e-i-farmaci-selettivi\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.messinamedica.it\/2024\/03\/mastocitosi-sistemica-nuove-prospettive-con-la-medicina-di-precisione-e-i-farmaci-selettivi\/<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>VIDEO INFORMAZIONI:<\/strong><\/p>\n\n\n\n<p>Link all\u2019articolo: <a href=\"https:\/\/videoinformazioni.com\/mastocitosi-sistemica-a-napoli-confronto-su-nuove-terapie\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/videoinformazioni.com\/mastocitosi-sistemica-a-napoli-confronto-su-nuove-terapie<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong><meta charset=\"utf-8\"><span style=\"color: #ff0000;\"><strong>Guarda i video:<\/strong><\/span><\/strong><\/p>\n\n\n\n<br>\n\n\n\n<p>PIANETA SALUTE:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mastocitosi Sistemica: Nuove Prospettive Terapeutiche e Avanzamenti nella Medicina di Precisione\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/5WBcucOoHQY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<br>\n\n\n\n<p><strong>ILTEMPO.IT &#8211; Cambio di traiettoria nel trattamento della mastocitosi sistemica<\/strong><\/p>\n\n\n\n<p>Vai al video: <a href=\"https:\/\/www.iltempo.it\/tv-news\/2024\/03\/01\/video\/cambio-di-traiettoria-nel-trattamento-della-mastocitosi-sistemica-38636993\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.iltempo.it\/tv-news\/2024\/03\/01\/video\/cambio-di-traiettoria-nel-trattamento-della-mastocitosi-sistemica-38636993\/<\/a><\/p>\n\n\n\n<br>\n\n\n\n<p><strong>In conclusione, sappiamo le sfide che ci sono da affrontare ogni giorno!<\/strong> La frustrazione, la paura, la solitudine. Ma volgiamo ribadire, ancora una volta, una cosa davvero importante: <strong>non siete soli!<\/strong><\/p>\n\n\n\n<p>Insieme a voi, combattiamo contro la mastocitosi. Insieme a voi, cerchiamo risposte e soluzioni. Insieme a voi, speriamo in un futuro migliore.<\/p>\n\n\n\n<p><strong>Il congresso DRIVE THE CHANGE \u00e8 stato un momento storico.<\/strong> La medicina di precisione ha aperto nuovi orizzonti per la cura della mastocitosi e ci sono nuove terapie, nuovi farmaci, nuove speranze.<\/p>\n\n\n\n<br>\n\n\n\n<p><strong>Continuiamo a camminare insieme s<\/strong><strong>ostenendoci a vicenda, dandoci forza, non perdendo mai la speranza!<\/strong><\/p>\n\n\n\n<p>Un abbraccio fortissimo,<\/p>\n\n\n\n<p>Asimas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MASTOCITOSI: 20 ANNI DOPO 29 Febbraio &#8211; 1 Marzo 2024: due giornate che resteranno indelebili nella memoria di tutti noi di Asimas. Invitati al congresso &#8220;DRIVE THE CHANGE&#8221; sponsorizzato da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[22,2],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>MASTOCITOSI: 20 ANNI DOPO - Asimas<\/title>\r\n<meta name=\"robots\" content=\"noindex, follow\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"MASTOCITOSI: 20 ANNI DOPO - Asimas\" \/>\r\n<meta property=\"og:description\" content=\"MASTOCITOSI: 20 ANNI DOPO 29 Febbraio &#8211; 1 Marzo 2024: due giornate che resteranno indelebili nella memoria di tutti noi di Asimas. Invitati al congresso &#8220;DRIVE THE CHANGE&#8221; sponsorizzato da [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Asimas\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-03-04T13:13:55+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-03-15T17:05:37+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/torta_logo_malattie_rare.jpg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dani\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#organization\",\"name\":\"ASIMAS - Associazione Italiana Mastocitosi\",\"url\":\"https:\/\/www.asimas.it\/new_asimas\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2019\/04\/logo-asimas.png\",\"contentUrl\":\"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2019\/04\/logo-asimas.png\",\"width\":240,\"height\":240,\"caption\":\"ASIMAS - Associazione Italiana Mastocitosi\"},\"image\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#website\",\"url\":\"https:\/\/www.asimas.it\/new_asimas\/\",\"name\":\"Asimas\",\"description\":\"Associazione Italiana Mastocitosi\",\"publisher\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asimas.it\/new_asimas\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/torta_logo_malattie_rare.jpg\",\"contentUrl\":\"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/torta_logo_malattie_rare.jpg\",\"width\":790,\"height\":584,\"caption\":\"Torta con il logo delle malattie rare\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#webpage\",\"url\":\"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/\",\"name\":\"MASTOCITOSI: 20 ANNI DOPO - Asimas\",\"isPartOf\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#primaryimage\"},\"datePublished\":\"2024-03-04T13:13:55+00:00\",\"dateModified\":\"2024-03-15T17:05:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.asimas.it\/new_asimas\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MASTOCITOSI: 20 ANNI DOPO\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#\/schema\/person\/f4cff0d0946e80b069d013531ab38b84\"},\"headline\":\"MASTOCITOSI: 20 ANNI DOPO\",\"datePublished\":\"2024-03-04T13:13:55+00:00\",\"dateModified\":\"2024-03-15T17:05:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#webpage\"},\"wordCount\":1228,\"publisher\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/torta_logo_malattie_rare.jpg\",\"articleSection\":[\"2024\",\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#\/schema\/person\/f4cff0d0946e80b069d013531ab38b84\",\"name\":\"Dani\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#personlogo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c03fe6a88949b182e89f15f862f46000?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c03fe6a88949b182e89f15f862f46000?s=96&d=mm&r=g\",\"caption\":\"Dani\"},\"url\":\"https:\/\/www.asimas.it\/new_asimas\/author\/admin\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MASTOCITOSI: 20 ANNI DOPO - Asimas","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"MASTOCITOSI: 20 ANNI DOPO - Asimas","og_description":"MASTOCITOSI: 20 ANNI DOPO 29 Febbraio &#8211; 1 Marzo 2024: due giornate che resteranno indelebili nella memoria di tutti noi di Asimas. Invitati al congresso &#8220;DRIVE THE CHANGE&#8221; sponsorizzato da [&hellip;]","og_url":"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/","og_site_name":"Asimas","article_published_time":"2024-03-04T13:13:55+00:00","article_modified_time":"2024-03-15T17:05:37+00:00","og_image":[{"url":"http:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/torta_logo_malattie_rare.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Dani","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.asimas.it\/new_asimas\/#organization","name":"ASIMAS - Associazione Italiana Mastocitosi","url":"https:\/\/www.asimas.it\/new_asimas\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.asimas.it\/new_asimas\/#logo","inLanguage":"it-IT","url":"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2019\/04\/logo-asimas.png","contentUrl":"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2019\/04\/logo-asimas.png","width":240,"height":240,"caption":"ASIMAS - Associazione Italiana Mastocitosi"},"image":{"@id":"https:\/\/www.asimas.it\/new_asimas\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.asimas.it\/new_asimas\/#website","url":"https:\/\/www.asimas.it\/new_asimas\/","name":"Asimas","description":"Associazione Italiana Mastocitosi","publisher":{"@id":"https:\/\/www.asimas.it\/new_asimas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asimas.it\/new_asimas\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/torta_logo_malattie_rare.jpg","contentUrl":"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/torta_logo_malattie_rare.jpg","width":790,"height":584,"caption":"Torta con il logo delle malattie rare"},{"@type":"WebPage","@id":"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#webpage","url":"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/","name":"MASTOCITOSI: 20 ANNI DOPO - Asimas","isPartOf":{"@id":"https:\/\/www.asimas.it\/new_asimas\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#primaryimage"},"datePublished":"2024-03-04T13:13:55+00:00","dateModified":"2024-03-15T17:05:37+00:00","breadcrumb":{"@id":"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asimas.it\/new_asimas\/"},{"@type":"ListItem","position":2,"name":"MASTOCITOSI: 20 ANNI DOPO"}]},{"@type":"Article","@id":"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#article","isPartOf":{"@id":"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#webpage"},"author":{"@id":"https:\/\/www.asimas.it\/new_asimas\/#\/schema\/person\/f4cff0d0946e80b069d013531ab38b84"},"headline":"MASTOCITOSI: 20 ANNI DOPO","datePublished":"2024-03-04T13:13:55+00:00","dateModified":"2024-03-15T17:05:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#webpage"},"wordCount":1228,"publisher":{"@id":"https:\/\/www.asimas.it\/new_asimas\/#organization"},"image":{"@id":"https:\/\/www.asimas.it\/new_asimas\/mastocitosi-20-anni-dopo\/#primaryimage"},"thumbnailUrl":"http:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2024\/03\/torta_logo_malattie_rare.jpg","articleSection":["2024","News"],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.asimas.it\/new_asimas\/#\/schema\/person\/f4cff0d0946e80b069d013531ab38b84","name":"Dani","image":{"@type":"ImageObject","@id":"https:\/\/www.asimas.it\/new_asimas\/#personlogo","inLanguage":"it-IT","url":"https:\/\/secure.gravatar.com\/avatar\/c03fe6a88949b182e89f15f862f46000?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c03fe6a88949b182e89f15f862f46000?s=96&d=mm&r=g","caption":"Dani"},"url":"https:\/\/www.asimas.it\/new_asimas\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/posts\/4908"}],"collection":[{"href":"https:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/comments?post=4908"}],"version-history":[{"count":22,"href":"https:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/posts\/4908\/revisions"}],"predecessor-version":[{"id":5004,"href":"https:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/posts\/4908\/revisions\/5004"}],"wp:attachment":[{"href":"https:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/media?parent=4908"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/categories?post=4908"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/tags?post=4908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}