{"id":2550,"date":"2019-05-20T00:37:10","date_gmt":"2019-05-19T22:37:10","guid":{"rendered":"http:\/\/www.asimas.it\/new_asimas\/?page_id=2550"},"modified":"2019-05-27T11:19:20","modified_gmt":"2019-05-27T09:19:20","slug":"13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati","status":"publish","type":"page","link":"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/","title":{"rendered":""},"content":{"rendered":"\r\n\r\n\r\n<div style=\"max-width: 750px;margin: 0 auto;padding: 10px;font-family: Arial, sans-serif;line-height: 1.6\">\r\n\r\n    <!-- Titolo e introduzione -->\r\n    <h1 style=\"color: #333;text-align: center\">Benvenuto su ASIMAS<\/h1>\r\n    <p style=\"font-size: 18px;color: #555;text-align: center\">\r\n        Quest'area \u00e8 dedicata agli utenti che hanno ricevuto l'approvazione, previa registrazione.\r\n    <\/p>\r\n\r\n    <!-- Box Login e Registrazione affiancati -->\r\n    <div style=\"margin-top: 40px;justify-content: space-between\">\r\n\r\n        <!-- Box Login -->\r\n        <div style=\"flex: 0 0 45%;background-color: #ffffff;padding: 15px;padding-bottom: 30px;border-radius: 10px;text-align: center\">\r\n            <!-- Icona Login -->\r\n            <div style=\"font-size: 40px;margin-bottom: 15px\">\ud83d\udc64<\/div>\r\n            <h2 style=\"color: #333\">Hai gi\u00e0 un account?<\/h2>\r\n            <p style=\"color: #000;font-size: 17px;margin-bottom:30px\">\r\n                Effettua il login per accedere all\u2019area riservata agli associati.\r\n            <\/p>\r\n\r\n            <!-- Bottone Login -->\r\n            <a href=\"http:\/\/www.asimas.it\/new_asimas\/login\/\" style=\"padding: 12px 25px;margin-top:30px;background-color: #a55969;color: #ffffff;text-decoration: none;border-radius: 10px;font-weight: bold\">\r\n                Vai al login\r\n            <\/a>\r\n        <\/div>\r\n\r\n        <!-- Box Registrazione -->\r\n        <div style=\"flex: 0 0 45%;background-color: #ffffff;margin-top:30px;padding: 15px;padding-bottom: 30px;border-radius: 10px;text-align: center\">\r\n            <!-- Icona Registrazione -->\r\n            <div style=\"font-size: 40px;margin-bottom: 15px\">\ud83d\udccb<\/div>\r\n            <h2 style=\"color: #333\">Non sei registrato\/a?<\/h2>\r\n            <p style=\"color: #000;font-size: 17px;margin-bottom:30px\">\r\n                Puoi registrarti in pochi passi e richiedere di diventare socio ASIMAS.\r\n            <\/p>\r\n\r\n            <!-- Bottone Registrazione -->\r\n            <a href=\"http:\/\/www.asimas.it\/new_asimas\/register\/\" style=\"padding: 12px 25px;background-color: #a55969;color: #ffffff;text-decoration: none;margin-top:30px;border-radius: 10px;font-weight: bold\">\r\n                Registrati ora\r\n            <\/a>\r\n        <\/div>\r\n\r\n    <\/div>\r\n\r\n    <!-- Box Perch\u00e9 associarsi -->\r\n    <div style=\"margin-top: 30px;background-color: #f2f2f2;padding: 30px;border-radius: 10px;text-align: center\">\r\n        <h2 style=\"color: #333\">Perch\u00e9 \u00e8 importante associarsi ad ASIMAS?<\/h2>\r\n        <p style=\"color: #000;font-size: 17px\">\r\n            Associarsi ad ASIMAS significa far parte di una comunit\u00e0 attiva e solidale, sostenere la ricerca scientifica e contribuire a diffondere consapevolezza sulla mastocitosi. Ogni socio diventa parte di un progetto concreto che aiuta chi convive con la malattia e rafforza la voce dell\u2019associazione a livello nazionale.\r\n        <\/p>\r\n    <\/div>\r\n\r\n<\/div>\r\n\r\n\r\n\r\n\r\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":2467,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.4.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>13 ottobre 2014 - resoconto stato avanzamento progetti di ricerca da noi finanziati - Asimas<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"13 ottobre 2014 - resoconto stato avanzamento progetti di ricerca da noi finanziati - Asimas\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Asimas\" \/>\r\n<meta property=\"article:modified_time\" content=\"2019-05-27T09:19:20+00:00\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#organization\",\"name\":\"ASIMAS - Associazione Italiana Mastocitosi\",\"url\":\"https:\/\/www.asimas.it\/new_asimas\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#logo\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2019\/04\/logo-asimas.png\",\"contentUrl\":\"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2019\/04\/logo-asimas.png\",\"width\":240,\"height\":240,\"caption\":\"ASIMAS - Associazione Italiana Mastocitosi\"},\"image\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#website\",\"url\":\"https:\/\/www.asimas.it\/new_asimas\/\",\"name\":\"Asimas\",\"description\":\"Associazione Italiana Mastocitosi\",\"publisher\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.asimas.it\/new_asimas\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/#webpage\",\"url\":\"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/\",\"name\":\"13 ottobre 2014 - resoconto stato avanzamento progetti di ricerca da noi finanziati - Asimas\",\"isPartOf\":{\"@id\":\"https:\/\/www.asimas.it\/new_asimas\/#website\"},\"datePublished\":\"2019-05-19T22:37:10+00:00\",\"dateModified\":\"2019-05-27T09:19:20+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.asimas.it\/new_asimas\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\",\"item\":\"http:\/\/www.asimas.it\/new_asimas\/utenti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\",\"item\":\"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\"}]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"13 ottobre 2014 - resoconto stato avanzamento progetti di ricerca da noi finanziati - Asimas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/","og_locale":"it_IT","og_type":"article","og_title":"13 ottobre 2014 - resoconto stato avanzamento progetti di ricerca da noi finanziati - Asimas","og_url":"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/","og_site_name":"Asimas","article_modified_time":"2019-05-27T09:19:20+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.asimas.it\/new_asimas\/#organization","name":"ASIMAS - Associazione Italiana Mastocitosi","url":"https:\/\/www.asimas.it\/new_asimas\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.asimas.it\/new_asimas\/#logo","inLanguage":"it-IT","url":"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2019\/04\/logo-asimas.png","contentUrl":"https:\/\/www.asimas.it\/new_asimas\/wp-content\/uploads\/2019\/04\/logo-asimas.png","width":240,"height":240,"caption":"ASIMAS - Associazione Italiana Mastocitosi"},"image":{"@id":"https:\/\/www.asimas.it\/new_asimas\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.asimas.it\/new_asimas\/#website","url":"https:\/\/www.asimas.it\/new_asimas\/","name":"Asimas","description":"Associazione Italiana Mastocitosi","publisher":{"@id":"https:\/\/www.asimas.it\/new_asimas\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asimas.it\/new_asimas\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/#webpage","url":"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/","name":"13 ottobre 2014 - resoconto stato avanzamento progetti di ricerca da noi finanziati - Asimas","isPartOf":{"@id":"https:\/\/www.asimas.it\/new_asimas\/#website"},"datePublished":"2019-05-19T22:37:10+00:00","dateModified":"2019-05-27T09:19:20+00:00","breadcrumb":{"@id":"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/13-ottobre-2014-resoconto-stato-avanzamento-progetti-di-ricerca-da-noi-finanziati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asimas.it\/new_asimas\/"},{"@type":"ListItem","position":2,"name":"","item":"http:\/\/www.asimas.it\/new_asimas\/utenti\/"},{"@type":"ListItem","position":3,"name":"","item":"http:\/\/www.asimas.it\/new_asimas\/utenti\/eventi\/"},{"@type":"ListItem","position":4,"name":""}]}]}},"_links":{"self":[{"href":"http:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/pages\/2550"}],"collection":[{"href":"http:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/comments?post=2550"}],"version-history":[{"count":1,"href":"http:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/pages\/2550\/revisions"}],"predecessor-version":[{"id":2551,"href":"http:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/pages\/2550\/revisions\/2551"}],"up":[{"embeddable":true,"href":"http:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/pages\/2467"}],"wp:attachment":[{"href":"http:\/\/www.asimas.it\/new_asimas\/wp-json\/wp\/v2\/media?parent=2550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}